{"id":42059,"date":"2026-03-06T11:21:31","date_gmt":"2026-03-06T10:21:31","guid":{"rendered":"https:\/\/julietteozouf.com\/produit\/white-leather-pouch\/"},"modified":"2026-03-06T11:40:30","modified_gmt":"2026-03-06T10:40:30","slug":"white-leather-pouch","status":"publish","type":"product","link":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/","title":{"rendered":"White leather pouch"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>We cannot offer all of our pieces on line! If you would like to see our other shirt models, you can contact us from Monday to Saturday from 12 p.m. to 7 p.m. on 01 43 29 74 51, or go to the store at 20 rue de l&#8217;\u00c9chaud\u00e9, Paris -75006. <\/strong><\/p>\n<p style=\"text-align: center;\">&#8211; How to enlarge a photo? Click on the image to see it in full screen.<\/p>\n<p style=\"text-align: center;\">&#8211; <em>Care instructions<\/em>: To guarantee the durability of your garment, hand washing is best. However, if you wish, you can machine wash following these specific instructions. For further information, we invite you to <a href=\"https:\/\/julietteozouf.com\/2022\/02\/09\/entretien-de-la-laine\/\" target=\"_blank\" rel=\"noopener\">click here<\/a>.<\/p>\n<p style=\"text-align: center;\">\u2013 <em>Good to know:<\/em> the colors represented in the photos on our site are as true as possible. However, we cannot guarantee exact colors which may vary as a function of your computer screen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"0\" data-end=\"79\">White leather pouch with adjustable shoulder strap and magnetic closure.<\/p>\n<p data-start=\"81\" data-end=\"170\" data-is-last-node=\"\" data-is-only-node=\"\">Each piece is unique.<br data-start=\"105\" data-end=\"108\">Other, slightly different models are also available.<\/p>\n","protected":false},"featured_media":42051,"template":"","meta":[],"product_brand":[],"product_cat":[257,260,256],"product_tag":[532,533,577],"class_list":["post-42059","product","type-product","status-publish","has-post-thumbnail","product_cat-accessories","product_cat-new-release","product_cat-women","product_tag-bag","product_tag-leather-en","product_tag-pouch","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>White leather pouch - Juliette Ozouf<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"White leather pouch - Juliette Ozouf\" \/>\n<meta property=\"og:description\" content=\"White leather pouch with adjustable shoulder strap and magnetic closure. Each piece is unique.Other, slightly different models are also available.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/\" \/>\n<meta property=\"og:site_name\" content=\"Juliette Ozouf\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/julietteozouf\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T10:40:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/julietteozouf.com\/wp-content\/uploads\/2026\/03\/sac-cuir-blanc-0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/produit\\\/white-leather-pouch\\\/\",\"url\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/produit\\\/white-leather-pouch\\\/\",\"name\":\"White leather pouch - Juliette Ozouf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/produit\\\/white-leather-pouch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/produit\\\/white-leather-pouch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/julietteozouf.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sac-cuir-blanc-0.jpg\",\"datePublished\":\"2026-03-06T10:21:31+00:00\",\"dateModified\":\"2026-03-06T10:40:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/produit\\\/white-leather-pouch\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/julietteozouf.com\\\/en\\\/produit\\\/white-leather-pouch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/produit\\\/white-leather-pouch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/julietteozouf.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sac-cuir-blanc-0.jpg\",\"contentUrl\":\"https:\\\/\\\/julietteozouf.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/sac-cuir-blanc-0.jpg\",\"width\":1280,\"height\":1588},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/produit\\\/white-leather-pouch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E -shop\",\"item\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/e-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"White leather pouch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/\",\"name\":\"Juliette Ozouf\",\"description\":\"Textiles incroyables\",\"publisher\":{\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/#organization\",\"name\":\"Juliette Ozouf\",\"url\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/julietteozouf.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/JULIETTE-OZOUF-FINAL-PETIT-100x71-1.jpg\",\"contentUrl\":\"https:\\\/\\\/julietteozouf.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/JULIETTE-OZOUF-FINAL-PETIT-100x71-1.jpg\",\"width\":100,\"height\":71,\"caption\":\"Juliette Ozouf\"},\"image\":{\"@id\":\"https:\\\/\\\/julietteozouf.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr-fr.facebook.com\\\/julietteozouf\",\"https:\\\/\\\/www.instagram.com\\\/julietteozouf\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"White leather pouch - Juliette Ozouf","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"White leather pouch - Juliette Ozouf","og_description":"White leather pouch with adjustable shoulder strap and magnetic closure. Each piece is unique.Other, slightly different models are also available.","og_url":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/","og_site_name":"Juliette Ozouf","article_publisher":"https:\/\/fr-fr.facebook.com\/julietteozouf","article_modified_time":"2026-03-06T10:40:30+00:00","og_image":[{"width":1280,"height":1588,"url":"https:\/\/julietteozouf.com\/wp-content\/uploads\/2026\/03\/sac-cuir-blanc-0.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/","url":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/","name":"White leather pouch - Juliette Ozouf","isPartOf":{"@id":"https:\/\/julietteozouf.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/#primaryimage"},"image":{"@id":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/#primaryimage"},"thumbnailUrl":"https:\/\/julietteozouf.com\/wp-content\/uploads\/2026\/03\/sac-cuir-blanc-0.jpg","datePublished":"2026-03-06T10:21:31+00:00","dateModified":"2026-03-06T10:40:30+00:00","breadcrumb":{"@id":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/#primaryimage","url":"https:\/\/julietteozouf.com\/wp-content\/uploads\/2026\/03\/sac-cuir-blanc-0.jpg","contentUrl":"https:\/\/julietteozouf.com\/wp-content\/uploads\/2026\/03\/sac-cuir-blanc-0.jpg","width":1280,"height":1588},{"@type":"BreadcrumbList","@id":"https:\/\/julietteozouf.com\/en\/produit\/white-leather-pouch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/julietteozouf.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"E -shop","item":"https:\/\/julietteozouf.com\/en\/e-shop\/"},{"@type":"ListItem","position":3,"name":"White leather pouch"}]},{"@type":"WebSite","@id":"https:\/\/julietteozouf.com\/en\/#website","url":"https:\/\/julietteozouf.com\/en\/","name":"Juliette Ozouf","description":"Textiles incroyables","publisher":{"@id":"https:\/\/julietteozouf.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/julietteozouf.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/julietteozouf.com\/en\/#organization","name":"Juliette Ozouf","url":"https:\/\/julietteozouf.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/julietteozouf.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/julietteozouf.com\/wp-content\/uploads\/2020\/07\/JULIETTE-OZOUF-FINAL-PETIT-100x71-1.jpg","contentUrl":"https:\/\/julietteozouf.com\/wp-content\/uploads\/2020\/07\/JULIETTE-OZOUF-FINAL-PETIT-100x71-1.jpg","width":100,"height":71,"caption":"Juliette Ozouf"},"image":{"@id":"https:\/\/julietteozouf.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/julietteozouf","https:\/\/www.instagram.com\/julietteozouf"]}]}},"_links":{"self":[{"href":"https:\/\/julietteozouf.com\/en\/wp-json\/wp\/v2\/product\/42059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/julietteozouf.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/julietteozouf.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/julietteozouf.com\/en\/wp-json\/wp\/v2\/media\/42051"}],"wp:attachment":[{"href":"https:\/\/julietteozouf.com\/en\/wp-json\/wp\/v2\/media?parent=42059"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/julietteozouf.com\/en\/wp-json\/wp\/v2\/product_brand?post=42059"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/julietteozouf.com\/en\/wp-json\/wp\/v2\/product_cat?post=42059"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/julietteozouf.com\/en\/wp-json\/wp\/v2\/product_tag?post=42059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}